{"id":9261,"date":"2024-05-06T13:02:07","date_gmt":"2024-05-06T11:02:07","guid":{"rendered":"https:\/\/firebox.com.ua\/?page_id=9261"},"modified":"2024-05-06T13:02:07","modified_gmt":"2024-05-06T11:02:07","slug":"otoplenye-dlya-bassejna-kupyt-v-ukrayne","status":"publish","type":"page","link":"https:\/\/firebox.com.ua\/ro\/otoplenye-dlya-bassejna-kupyt-v-ukrayne\/","title":{"rendered":"Cump\u0103ra\u021bi \u00eenc\u0103lzire pentru piscin\u0103 \u00een Ucraina"},"content":{"rendered":"<section class=\"section slider-thumb-pool\" id=\"section_232134484\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1974273578\">\n\n\t<div id=\"col-1764932715\" class=\"col medium-8 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1613112865\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1613112865 {\n  padding-top: 35px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-2059658641\" class=\"gap-element clearfix show-for-medium hide-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2059658641 {\n  padding-top: 60px;\n}\n@media (min-width:850px) {\n  #gap-2059658641 {\n    padding-top: 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-315903253\" class=\"gap-element clearfix show-for-medium\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-315903253 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_329324609\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"73\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/logo-focus-rgb-jekran-prozrachnyj-fon-e1714926778114.png\" class=\"attachment-large size-large\" alt=\"Cazane modulare FOCUS TERMO\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/logo-focus-rgb-jekran-prozrachnyj-fon-e1714926778114.png 200w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/logo-focus-rgb-jekran-prozrachnyj-fon-e1714926778114-18x7.png 18w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_329324609 {\n  width: 49%;\n}\n@media (min-width:550px) {\n  #image_329324609 {\n    width: 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1257504725\" class=\"gap-element clearfix show-for-medium hide-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1257504725 {\n  padding-top: 0px;\n}\n@media (min-width:850px) {\n  #gap-1257504725 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-352232313\" class=\"text show-for-small\">\n\t\t\n<h1 class=\"lead\">\u00cenc\u0103lzire \u00een toate anotimpurile<br \/>\npiscin\u0103?<\/h1>\n\t\t\n<style>\n#text-352232313 {\n  color: rgb(0,0,0);\n}\n#text-352232313 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1118988307\" class=\"gap-element clearfix show-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1118988307 {\n  padding-top: 430px;\n}\n@media (min-width:550px) {\n  #gap-1118988307 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1764932715 > .col-inner {\n  padding: 0px 0px 0px 10%;\n}\n@media (min-width:850px) {\n  #col-1764932715 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1685138132\" class=\"col hide-for-small medium-4 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(229, 210, 108, 0.5);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-311623492\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-311623492 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1407064182\" class=\"text\">\n\t\t\n<h1 class=\"uppercase\" style=\"color: black;\">\u00cenc\u0103lzirea piscinei pe tot sezonul?<\/h1>\n\t\t\n<style>\n#text-1407064182 {\n  font-size: 0.9rem;\n  color: rgb(0,0,0);\n}\n#text-1407064182 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:170px;background-color:rgba(253, 247, 247, 0.465);\"><\/div>\n\t<div id=\"text-1800911321\" class=\"text hide-for-medium\">\n\t\t\n<p style=\"font-size: 100%; line-height: 1.5;\">Una dintre caracteristicile de \u00eentre\u021binere este \u00eenc\u0103lzirea \u00een toate anotimpurile a piscinelor, care este de a\u0219teptat s\u0103 fie foarte scump\u0103 atunci c\u00e2nd se folosesc combustibili tradi\u021bionali. Coopera\u021bi cu compania noastr\u0103 dac\u0103 sunte\u021bi interesat de controlul inteligent al \u00eenc\u0103lzirii piscinei, \u00eenc\u0103lzirea piscinelor multiple \u0219i autonomie complet\u0103.<\/p>\n<p style=\"font-size: 100%; line-height: 1.5;\">FOCUS TERMO ofera cazane pentru incalzirea piscinelor cu economii de peste 70% din costul gazului care ar putea fi cheltuit in aceste scopuri.<\/p>\n\t\t\n<style>\n#text-1800911321 {\n  color: rgb(0,0,0);\n}\n#text-1800911321 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-498984940\" class=\"text show-for-medium hide-for-small\">\n\t\t\n<p style=\"font-size: 100%; line-height: 1.5;\">Una dintre caracteristicile de \u00eentre\u021binere este \u00eenc\u0103lzirea \u00een toate anotimpurile a piscinelor, care este de a\u0219teptat s\u0103 fie foarte scump\u0103 atunci c\u00e2nd se folosesc combustibili tradi\u021bionali.<\/p>\n<p style=\"font-size: 100%; line-height: 1.5;\">FOCUS TERMO ofera cazane pentru incalzirea piscinelor cu economii de peste 70% din costul gazului care ar putea fi cheltuit in aceste scopuri.<\/p>\n\t\t\n<style>\n#text-498984940 {\n  color: rgb(0,0,0);\n}\n#text-498984940 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1685138132 > .col-inner {\n  padding: 0px 20px 20px 20px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_232134484 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row show-for-small\"  id=\"row-131051365\">\n\n\t<div id=\"col-1955040846\" class=\"col medium-4 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-2033816133\" class=\"gap-element clearfix hide-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2033816133 {\n  padding-top: 50px;\n}\n@media (min-width:550px) {\n  #gap-2033816133 {\n    padding-top: 100px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-4291275914\" class=\"text hide-for-small\">\n\t\t\n<h1 class=\"uppercase\" style=\"color: black;\">\u00cenc\u0103lzirea piscinei pe tot sezonul?<\/h1>\n\t\t\n<style>\n#text-4291275914 {\n  color: rgb(0,0,0);\n}\n#text-4291275914 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:170px;background-color:rgba(253, 247, 247, 0.465);\"><\/div>\n\t<div id=\"text-778622550\" class=\"text\">\n\t\t\n<p style=\"font-size: 100%; line-height: 1.5;\">Una dintre caracteristicile de \u00eentre\u021binere este \u00eenc\u0103lzirea \u00een toate anotimpurile a piscinelor, care este de a\u0219teptat s\u0103 fie foarte scump\u0103 atunci c\u00e2nd se folosesc combustibili tradi\u021bionali.<\/p>\n<p style=\"font-size: 100%; line-height: 1.5;\">FOCUS TERMO ofera cazane pentru incalzirea piscinelor cu economii de peste 70% din costul gazului care ar putea fi cheltuit in aceste scopuri.<\/p>\n\t\t\n<style>\n#text-778622550 {\n  color: rgb(0,0,0);\n}\n#text-778622550 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1955040846 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse row-full-width Small_window\"  id=\"row-407793099\">\n\n\t<div id=\"col-315863040\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover features\" id=\"banner-1107615922\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                    <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-866577582\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<h4 class=\"uppercase\">Camere de cazane la cheie<br \/>\npentru piscine mici<\/h4>\n<h2 class=\"uppercase\" style=\"font-size: 240%;\">Minicazane cu pele\u021bi<\/h2>\n<a href=\"\/ro\/tverdotoplivnye-pelletnye-kotly\/pelletnyj-kotel-20-kvt-focus-diapazon-moshhnosti-5-25kvt\/\" class=\"button white is-outline is-xlarge\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-866577582 {\n  width: 70%;\n}\n#text-box-866577582 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1107615922 {\n  padding-top: 250px;\n  background-color: rgb(137, 196, 144);\n}\n#banner-1107615922 .overlay {\n  background-color: rgba(0, 0, 0, 0.12);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-315863040 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-315863040 > .col-inner {\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1041619897\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover features1 bg-zoom-fade\" id=\"banner-2102880947\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                    <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-997673970\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<h4 class=\"uppercase\">Oferi<br \/>\npentru piscine mari<\/h4>\n<h2 class=\"uppercase\" style=\"font-size: 240%;\">Cascad\u0103<br \/>\ncamerele cazanelor<\/h2>\n<a href=\"\/ro\/tverdotoplivnye-pelletnye-kotly\/\" class=\"button white is-outline is-xlarge\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-997673970 {\n  width: 70%;\n}\n#text-box-997673970 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2102880947 {\n  padding-top: 250px;\n  background-color: rgb(137, 196, 144);\n}\n#banner-2102880947 .overlay {\n  background-color: rgba(0, 0, 0, 0.2);\n}\n#banner-2102880947 .banner-bg img {\n  object-position: 50% 57%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1041619897 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1041619897 > .col-inner {\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1323216761\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover features2 bg-zoom-fade\" id=\"banner-341988029\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                    <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-768968432\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<h4 class=\"uppercase\">F\u0103r\u0103 \u00eentre\u021binere<br \/>\ncamerele cazanelor<\/h4>\n<h2 class=\"uppercase\" style=\"font-size: 240%;\">Cazane cu curatare pneumatica<\/h2>\n<a href=\"\/ro\/samoochistnye-pelletnye-kotly\/\" class=\"button white is-outline is-xlarge\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-768968432 {\n  width: 70%;\n}\n#text-box-768968432 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-341988029 {\n  padding-top: 250px;\n  background-color: rgb(137, 196, 144);\n}\n#banner-341988029 .overlay {\n  background-color: rgba(0, 0, 0, 0.13);\n}\n#banner-341988029 .banner-bg img {\n  object-position: 31% 0%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1323216761 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1323216761 > .col-inner {\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1910417525\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1910417525 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-full-width align-center\"  id=\"row-1931812135\">\n\n\t<div id=\"col-443000765\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auto_power.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auto_power.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auto_power-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auto_power-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auto_power-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Pornire automat\u0103<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-203655892\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Indiferent de tipul de instala\u021bie, camerele de cazane FOCUS TERMO sunt conectate automat pe baza citirilor senzorilor.<\/p>\n\t\t\n<style>\n#text-203655892 {\n  color: rgb(0,0,0);\n}\n#text-203655892 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-503966645\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auatomats.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auatomats.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auatomats-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auatomats-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/auatomats-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Complet automat<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-2306800784\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Func\u021bionarea automat\u0103 combinat\u0103 cu independen\u021ba fa\u021b\u0103 de re\u021belele de alimentare cu gaz este o caracteristic\u0103 avantajoas\u0103 a \u00eenc\u0103lzirii FOCUS TERMO.<\/p>\n\t\t\n<style>\n#text-2306800784 {\n  color: rgb(0,0,0);\n}\n#text-2306800784 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-896668415\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/pellets.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/pellets.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/pellets-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/pellets-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/pellets-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Combustibil de cenu\u0219\u0103<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-548000538\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Utiliza\u021bi combustibil cu con\u021binut ridicat de cenu\u0219\u0103 f\u0103r\u0103 a deteriora schimb\u0103torul de c\u0103ldur\u0103 \u0219i eficien\u021ba datorit\u0103 arderii ulterioare prin piroliz\u0103.<\/p>\n\t\t\n<style>\n#text-548000538 {\n  color: rgb(0,0,0);\n}\n#text-548000538 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-177567775\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/effects.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/effects.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/effects-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/effects-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/effects-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Eficien\u021b\u0103 maxim\u0103<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-2135196679\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Schimb\u0103torul de c\u0103ldur\u0103 eterogen este o caracteristic\u0103 distinctiv\u0103 a cazanelor FOCUS TERMO. Tubul \u0219i placa elimin\u0103 c\u0103ldura cu o eficien\u021b\u0103 de 96%.<\/p>\n\t\t\n<style>\n#text-2135196679 {\n  color: rgb(0,0,0);\n}\n#text-2135196679 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1701471555\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/wheater_regulation.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/wheater_regulation.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/wheater_regulation-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/wheater_regulation-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/wheater_regulation-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Control climatic<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-866930640\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Conecta\u021bi \u00eenc\u0103lzirea piscinei la controlul climatiz\u0103rii \u0219i controla\u021bi temperatura folosind indicatori complexi.<\/p>\n\t\t\n<style>\n#text-866930640 {\n  color: rgb(0,0,0);\n}\n#text-866930640 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-862003025\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/scenarious.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/scenarious.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/scenarious-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/scenarious-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/scenarious-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Controlul panoului<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-2856751156\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Controla\u021bi temperatura piscinei sau a zonelor de \u00eenc\u0103lzire folosind panoul tactil, f\u0103r\u0103 a cump\u0103ra un hidromasaj.<\/p>\n\t\t\n<style>\n#text-2856751156 {\n  color: rgb(0,0,0);\n}\n#text-2856751156 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-391720440\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/user_scenarious.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/user_scenarious.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/user_scenarious-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/user_scenarious-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/user_scenarious-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Gestionarea scenariilor<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-26265806\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Gestiona\u021bi scenariile de \u00eenc\u0103lzire a piscinei, reduc\u00e2nd costurile cu combustibilul.<\/p>\n\t\t\n<style>\n#text-26265806 {\n  color: rgb(0,0,0);\n}\n#text-26265806 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-995199981\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  style=\"margin:5px 5px 5px 5px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"170\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/climat_control.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/climat_control.png 170w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/climat_control-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/climat_control-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/climat_control-12x12.png 12w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" title=\"- -\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Controlul vremii<\/h5>\t\t\t\t\t\t\n\t<div id=\"text-2949328897\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">\u00cen func\u021bie de scenarii, \u00eenc\u0103lzirea piscinei va ajusta temperatura la datele meteo.<\/p>\n\t\t\n<style>\n#text-2949328897 {\n  color: rgb(0,0,0);\n}\n#text-2949328897 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1931812135 > .col > .col-inner {\n  padding: 5% 5% 5% 5%;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-905011761\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-905011761 {\n  padding-top: 80px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle align-center\"  id=\"row-1387951199\">\n\n\t<div id=\"col-899213419\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1604144190\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\" style=\"font-size: 180%; font-weight: 900;\">Beneficiile tale<\/h2>\n<h3>la achizi\u021bionarea \u00eenc\u0103lzirii piscinei<\/h3>\n<p style=\"font-size: 150%; color: #fab331;\">FOCUS TERMO ePOOL<\/p>\n\t\t\n<style>\n#text-1604144190 {\n  color: rgb(0,0,0);\n}\n#text-1604144190 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1953182420\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1953182420 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle align-center\"  id=\"row-1258295261\">\n\n\t<div id=\"col-2119585558\" class=\"col medium-12 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(250, 211, 75);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2029093185\" class=\"text\">\n\t\t\n<h3 style=\"color: black;\">70% economii<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Vei economisi p\u00e2n\u0103 la 70+% din pre\u021bul gazului la \u00eenc\u0103lzirea unei piscine cu centralele pe pele\u021bi FOCUS TERMO \u0219i po\u021bi folosi \u0219i orice pele\u021bi cu con\u021binut ridicat de cenu\u0219\u0103, inclusiv cele de cas\u0103, pentru a completa rezervele de combustibil.<\/p>\n\t\t\n<style>\n#text-2029093185 {\n  color: rgb(0,0,0);\n}\n#text-2029093185 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2119585558 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-645941008\" class=\"col medium-12 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(250, 211, 75);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3583262927\" class=\"text\">\n\t\t\n<h3 style=\"color: black;\">Complet automat<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">\u00cenc\u0103lzirea piscinei de la FOCUS este un echipament de \u00eenc\u0103lzire complet automat, care \u00een mod oficial necesit\u0103 doar completarea bunc\u0103rului de pele\u021bi \u0219i \u00eentre\u021binere regulat\u0103.<\/p>\n\t\t\n<style>\n#text-3583262927 {\n  color: rgb(0,0,0);\n}\n#text-3583262927 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-645941008 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1762263693\" class=\"col medium-12 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(250, 211, 75);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-615310196\" class=\"text\">\n\t\t\n<h3 style=\"color: black;\">Autonomie total\u0103<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Cu cazanele pe pele\u021bi FOCUS TERMO nu depinde\u021bi de re\u021bele dac\u0103 ave\u021bi nevoie de \u00eenc\u0103lzire ieftin\u0103 a piscinei, cu posibilitatea de a regla parametrii climatici ai \u00eenc\u0103perii \u00een combina\u021bie cu algoritmi \u0219i scenarii meteo.<\/p>\n\t\t\n<style>\n#text-615310196 {\n  color: rgb(0,0,0);\n}\n#text-615310196 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1762263693 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_681270369\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-933391843\">\n\n\t<div id=\"col-1284289353\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-540041821\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%; line-height: 1.6;\">\u00cenc\u0103lzirea pentru o piscin\u0103 poate fi implementat\u0103 \u00een acela\u0219i mod ca \u0219i \u00eenc\u0103lzirea inteligent\u0103 a caselor, cl\u0103dirilor \u0219i structurilor. Mai mult, pute\u021bi instala o boiler independent\u0103 sau conecta\u021bi echipamentele existente la o cascad\u0103 de cazane pe pele\u021bi, ceea ce v\u0103 va rezolva problemele \u0219i va reduce costul \u00eenc\u0103lzirii unei case mari.<\/p>\n<p style=\"font-size: 90%; line-height: 1.6;\">Cu ajutorul lor, f\u0103r\u0103 a pune presiune pe buget, pute\u021bi asigura \u00eenc\u0103lzirea piscinei, care este ajustat\u0103 automat \u00een func\u021bie de scenariile utilizatorului \u0219i condi\u021biile meteorologice. <strong>Este convenabil, ra\u021bional, confortabil \u0219i ieftin!<\/strong><\/p>\n\t\t\n<style>\n#text-540041821 {\n  text-align: left;\n  color: rgb(0,0,0);\n}\n#text-540041821 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2039393618\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3457736819\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%; line-height: 1.6;\">Incalzirea piscinei pe baza de cazane automate pe peleti FOCUS TERMO ePOOL este o solutie scalabila. Cazanele pot furniza c\u0103ldur\u0103 controlat\u0103 de program complexelor sportive mari cu mai multe piscine sau o zon\u0103 mic\u0103 de spa \u00eentr-o parcel\u0103 personal\u0103.<\/p>\n<p style=\"font-size: 90%; line-height: 1.6;\">Acest lucru se realizeaz\u0103 atunci c\u00e2nd se utilizeaz\u0103 modele de cazane pe pele\u021bi cu o putere de p\u00e2n\u0103 la 30 kW sau se utilizeaz\u0103 cazane \u00een cascad\u0103, a c\u0103ror putere este scalat\u0103. <strong>p\u00e2n\u0103 la 2,2 MW<\/strong>.<\/p>\n\t\t\n<style>\n#text-3457736819 {\n  text-align: left;\n  color: rgb(0,0,0);\n}\n#text-3457736819 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_681270369 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"text-3713812267\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\" style=\"font-size: 180%; font-weight: 900;\">Op\u021biuni de instalare a cazanului<\/h2>\n<p style=\"font-size: 150%; color: #fab331;\">FOCUS TERMO ePOOL<\/p>\n\t\t\n<style>\n#text-3713812267 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-691792229\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-691792229 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-1652627062\">\n\n\t<div id=\"col-1369671250\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-3111040874\" class=\"text\">\n\t\t\n<h3>\u00cen \u00eenc\u0103peri \u00eengropate \u00een p\u0103m\u00e2nt<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Dimensiunile compacte ale cazanelor pe pele\u021bi le permit s\u0103 fie amplasate \u00eentr-o \u00eenc\u0103pere mic\u0103 l\u00e2ng\u0103 o piscin\u0103, cu doar eliminarea gazelor de ardere.<\/p>\n\t\t\n<style>\n#text-3111040874 {\n  color: rgb(0,0,0);\n}\n#text-3111040874 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1369671250 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1076599004\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-1126959478\" class=\"text\">\n\t\t\n<h3>Modular<br \/>\ncamerele cazanelor<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Utiliza\u021bi camere de cazane modulare pentru a conecta sistemul de \u00eenc\u0103lzire a piscinei la \u00eenc\u0103lzire f\u0103r\u0103 lucr\u0103ri suplimentare de construc\u021bie pe \u0219antier.<\/p>\n\t\t\n<style>\n#text-1126959478 {\n  color: rgb(0,0,0);\n}\n#text-1126959478 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1076599004 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1035465548\" class=\"col medium-12 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-3657944802\" class=\"text\">\n\t\t\n<h3>Cazan\u0103 comun\u0103 pentru cas\u0103 \u0219i cl\u0103dire<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Inlocuirea echipamentelor de incalzire cu FOCUS TERMO va asigura caldura ieftina nu doar casei, ci si piscinei, cu autonomie completa pentru gospodarie.<\/p>\n\t\t\n<style>\n#text-3657944802 {\n  color: rgb(0,0,0);\n}\n#text-3657944802 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1035465548 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_546120537\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-2022280189\">\n\n\t<div id=\"col-2126627758\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-80376214\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%; line-height: 1.6;\">\u00cenc\u0103lzirea unei piscine necesit\u0103 dezvoltarea unui proiect separat, care are o serie de cerin\u021be. \u00cen primul r\u00e2nd, se calculeaz\u0103 suprafa\u021ba schimb\u0103torului de c\u0103ldur\u0103 al piscinei capabil s\u0103 \u00eenc\u0103lzi un volum mare de ap\u0103. Din acest motiv, dac\u0103 decide\u021bi s\u0103 face\u021bi un centru spa all-season acas\u0103 sau \u00eentr-un complex sportiv, ve\u021bi avea nevoie de o dezvoltare detaliat\u0103 a unui proiect de \u00eenc\u0103lzire a piscinei. <strong>Compania noastr\u0103 va efectua aceste lucr\u0103ri pentru dvs.<\/strong><\/p>\n<p style=\"font-size: 90%; line-height: 1.6;\">Dac\u0103 ave\u021bi o piscin\u0103 gata f\u0103cut\u0103 \u0219i dori\u021bi s\u0103 instala\u021bi \u00eenc\u0103lzirea apei, contacta\u021bi compania sau reprezentantul nostru pentru a clarifica detaliile tehnice \u0219i a evalua posibilitatea instal\u0103rii \u00eenc\u0103lzirii pe baza cazanelor pe pele\u021bi FOCUS TERMO ePOOL.<\/p>\n\t\t\n<style>\n#text-80376214 {\n  color: rgb(0,0,0);\n}\n#text-80376214 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1202275292\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3511774616\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%; line-height: 1.6;\">O caracteristic\u0103 a cazanelor pe pele\u021bi este scalabilitatea destul de u\u0219oar\u0103 a \u00eenc\u0103lzirii; este suficient s\u0103 conecta\u021bi echipamente suplimentare de \u00eenc\u0103lzire \u00eentr-o cascad\u0103 \u0219i pute\u021bi cre\u0219te puterea unui cazan \u00een cluster la 2,2 MW sau mai mult.<\/p>\n<p style=\"font-size: 90%; line-height: 1.6;\">FOCUS TERMO poate realiza proiecte complexe de echipare si incalzire a piscinelor hotelierelor, a centrelor balneare, a cluburilor sportive si a parcurilor acvatice. Inclusiv cei \u00eendep\u0103rta\u021bi de re\u021belele ora\u0219ului \u0219i care opereaz\u0103 OFFGRID. <strong>Al\u0103tura\u021bi-v\u0103 partenerilor no\u0219tri pentru a implementa solu\u021bii de \u00eenc\u0103lzire \u00eendr\u0103zne\u021be pentru instala\u021bii complexe!<\/strong><\/p>\n\t\t\n<style>\n#text-3511774616 {\n  color: rgb(0,0,0);\n}\n#text-3511774616 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_546120537 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-330234449\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-330234449 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3580096440\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\" style=\"font-size: 180%; font-weight: 900;\">Iti recomandam<\/h2>\n<p style=\"font-size: 150%; color: #fab331;\">FOCUS TERMO ePOOL<\/p>\n\t\t\n<style>\n#text-3580096440 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1682072125\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1682072125 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-1669452861\">\n\n\t<div id=\"col-1344117883\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-834193863\" class=\"text\">\n\t\t\n<h3>Pentru case<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Crea\u021bi o piscin\u0103 pentru toate anotimpurile \u00een gr\u0103dina dvs. V\u0103 pute\u021bi bucura de zona de hidromasaj, pute\u021bi face o piscin\u0103 pentru copii deschis\u0103 pe tot parcursul anului.<\/p>\n\t\t\n<style>\n#text-834193863 {\n  color: rgb(0,0,0);\n}\n#text-834193863 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1344117883 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2078577502\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-3717229643\" class=\"text\">\n\t\t\n<h3>Pentru hoteluri<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">A avea o piscin\u0103 \u00eentr-un hotel este unul dintre factorii de prestigiu. FOCUS TERMO va ajuta la reducerea costurilor de \u00eentre\u021binere \u0219i \u00eenc\u0103lzire a piscinei cu 70% din pre\u021bul gazului.<\/p>\n\t\t\n<style>\n#text-3717229643 {\n  color: rgb(0,0,0);\n}\n#text-3717229643 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2078577502 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1474517204\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-4002688017\" class=\"text\">\n\t\t\n<h3>Pentru centre de birouri<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">\u00cenchirierea spa\u021biilor de birouri \u0219i depozite este o afacere profitabil\u0103, dar po\u021bi cre\u0219te prestigiul unui birou sau centru comercial prin crearea unui complex sportiv cu piscin\u0103.<\/p>\n\t\t\n<style>\n#text-4002688017 {\n  color: rgb(0,0,0);\n}\n#text-4002688017 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1474517204 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-116512908\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-3841681051\" class=\"text\">\n\t\t\n<h3>Pentru centrele spa<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Centrele spa sunt specializate \u00een diverse tratamente cu ap\u0103 \u0219i relaxare \u00een piscine. Cu FOCUS TERMO pute\u021bi reduce semnificativ costurile de \u00eenc\u0103lzire a piscinei.<\/p>\n\t\t\n<style>\n#text-3841681051 {\n  color: rgb(0,0,0);\n}\n#text-3841681051 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-116512908 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-577258120\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-823037000\" class=\"text\">\n\t\t\n<h3>Pentru complexe sportive<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Cu FOCUS TERMO pute\u021bi construi un complex mare cu mai multe piscine \u0219i \u00eel pute\u021bi face rentabil \u0219i rentabil, baz\u00e2nd pe costuri mici de \u00eenc\u0103lzire a piscinei.<\/p>\n\t\t\n<style>\n#text-823037000 {\n  color: rgb(0,0,0);\n}\n#text-823037000 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-577258120 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-951817646\" class=\"col medium-6 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-2408715862\" class=\"text\">\n\t\t\n<h3>Pentru parcuri acvatice<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Dac\u0103 v\u0103 confrunta\u021bi cu problema optimiz\u0103rii \u00eenc\u0103lzirii piscinelor din parcurile acvatice, FOCUS TERMO ePOOL v\u0103 va ajuta s\u0103 reduce\u021bi consumul la un minim avantajos cu costuri de instalare accesibile.<\/p>\n\t\t\n<style>\n#text-2408715862 {\n  color: rgb(0,0,0);\n}\n#text-2408715862 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-951817646 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1599887088\" class=\"col medium-6 small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n<div class=\"message-box relative dark\" style=\"padding-top:15px;padding-bottom:15px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(250, 211, 75);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n<div class=\"row align-middle align-center\"  id=\"row-948176351\">\n\n\t<div id=\"col-1563376074\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1422352224\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1422352224 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3439582887\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%; line-height: 1.7;\">Pute\u021bi contacta managerul de direc\u021bie,<br \/>\nPentru a v\u0103 clarifica \u00eentreb\u0103rile:<\/p>\n<p><strong>SRL \u201eAqua Empire\u201d<\/strong>:<br \/>Telefon: <a href=\"tel:+38067612 0614\">+380 67 612 06 14<\/a>,<br \/>E-mail: <a \nhref=\"mailto:Akbass@ukr.net\">Akbass@ukr.net<\/a><\/p>\n\t\t\n<style>\n#text-3439582887 {\n  color: rgb(0,0,0);\n}\n#text-3439582887 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1319206249\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1319206249 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-294661843\" class=\"col medium-5 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<a data-animate=\"bounceInUp\" href=\"\/ro\/contact-us\/\" class=\"button white is-outline is-large\" style=\"border-radius:99px;\">\n\t<i class=\"icon-heart-o\" aria-hidden=\"true\"><\/i>\t<span>comanda un calcul<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1215826796\" class=\"gap-element clearfix show-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1215826796 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<\/div><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-114915806\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-114915806 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-1771883715\">\n\n\t<div id=\"col-1012680707\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4276451871\" class=\"text\">\n\t\t\n<h2>Cazane FOCUS TERMO<br \/>\npentru incalzirea piscinei<\/h2>\n<h3 style=\"color: #464646;\">la preturi accesibile<\/h3>\n<h3>\n\t\t\n<style>\n#text-4276451871 {\n  color: rgb(0,0,0);\n}\n#text-4276451871 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"stack-3790176256\" class=\"stack stack-row justify-start items-stretch sm:stack-col sm:items-stretch\">\n\t\t\n\t<div id=\"text-761193798\" class=\"text\">\n\t\t\n<\/h3>\n\t\t\t<\/div>\n\t\n\t<div id=\"text-1123794119\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-782373111\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-3500358504\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-1158013965\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-3555251964\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-3231147851\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-1741558775\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-437370626\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-1552628686\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-607344984\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"text-396700511\" class=\"text\">\n\t\t\n\t\t\t<\/div>\n\t\n\t<div id=\"gap-1903989507\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1903989507 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1219708687\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"Camerele cazanelor cu cazane pe combustibil solid cu arz\u0103toare pe pele\u021bi pot fi utilizate \u00een fabricile de produc\u021bie pentru a satisface diverse nevoi de c\u0103ldur\u0103 \u0219i energie\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-768x1024.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-510x680.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-225x300.jpg 225w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-9x12.jpg 9w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193.jpg 750w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1219708687 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_761687642\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:40px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2.png\" class=\"attachment-large size-large\" alt=\"cazan pe pele\u021bi FOCUS 100 kW, cazan pe pele\u021bi FOCUS 120 kW asamblat cu un arz\u0103tor pe pele\u021bi cu trei compartimente func\u021bionale (schimb\u0103tor de c\u0103ldur\u0103 orizontal, camer\u0103 de ardere, cenu\u0219\u0103), echipat cu un sistem de \u00eendep\u0103rtare a cenu\u0219ii cu \u0219urub \u00een containere rulante. Ofer\u0103 intervale crescute \u00eentre cur\u0103\u021b\u0103rile cazanului, cresc\u00e2nd timpul de generare continu\u0103 a c\u0103ldurii, care este deosebit de critic \u00een fabrici, sere \u0219i alte unit\u0103\u021bi unde stabilitatea furniz\u0103rii de c\u0103ldur\u0103 este important\u0103. Centrala este echipat\u0103 cu arz\u0103tor automat pe pele\u021bi, func\u021bionarea cu \u00eenc\u0103rcare manual\u0103 a combustibilului nu este prev\u0103zut\u0103 de proiectarea cazanului. Recipient de cenusa glisant, Cazan pe peleti FOCUS 150 kW, Cazan pe peleti 60 kW FOCUS, Cazan pe peleti 70 kW FOCUS, Cazan pe peleti 80 kW FOCUS\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_761687642 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2077118558\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-513-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"Camere de cazane modulare FOCUS\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-513-768x1024.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-513-510x680.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-513-225x300.jpg 225w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-513-9x12.jpg 9w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-513.jpg 750w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2077118558 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_328851961\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:40px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"510\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva.jpg\" class=\"attachment-large size-large\" alt=\"Cazane pe combustibil solid cu arzator pe peleti. Cazan pe pele\u021bi cu \u00eenc\u0103rcare manual\u0103 op\u021bional\u0103 a combustibilului TT\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-100x100.jpg 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-300x300.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-150x150.jpg 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-12x12.jpg 12w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_328851961 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1318769275\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-20-569-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"Camere de cazane modulare FOCUS\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-20-569-768x1024.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-20-569-510x680.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-20-569-225x300.jpg 225w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-20-569-9x12.jpg 9w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-20-569.jpg 750w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1318769275 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_792779826\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:40px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30.png\" class=\"attachment-large size-large\" alt=\"Cazan mono-pele\u021bi 60 kW. Cazan pe pele\u021bi de uz casnic Mono-pele\u021bi 50 kW, cazan pe pele\u021bi Mono-pele\u021bi 75 kW, cazan pe pele\u021bi Mono-pele\u021bi 90 kW cu climatizare \u00een format monobloc.\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_792779826 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t\n<style>\n#stack-3790176256 > * {\n  --stack-gap: 0.75rem;\n}\n@media (min-width:550px) {\n  #stack-3790176256 > * {\n    --stack-gap: 0rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>&nbsp;<\/p>\n\t<div id=\"gap-74374726\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-74374726 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-996247132\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\" style=\"font-size: 180%; font-weight: 900;\">Kit de instalare a cazanului<\/h2>\n<p style=\"font-size: 150%; color: #fab331;\">FOCUS TERMO ePOOL<\/p>\n\t\t\n<style>\n#text-996247132 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1797352572\">\n\n\t<div id=\"col-511697\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_641763946\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2.png\" class=\"attachment-large size-large\" alt=\"cazan pe pele\u021bi FOCUS 100 kW, cazan pe pele\u021bi FOCUS 120 kW asamblat cu un arz\u0103tor pe pele\u021bi cu trei compartimente func\u021bionale (schimb\u0103tor de c\u0103ldur\u0103 orizontal, camer\u0103 de ardere, cenu\u0219\u0103), echipat cu un sistem de \u00eendep\u0103rtare a cenu\u0219ii cu \u0219urub \u00een containere rulante. Ofer\u0103 intervale crescute \u00eentre cur\u0103\u021b\u0103rile cazanului, cresc\u00e2nd timpul de generare continu\u0103 a c\u0103ldurii, care este deosebit de critic \u00een fabrici, sere \u0219i alte unit\u0103\u021bi unde stabilitatea furniz\u0103rii de c\u0103ldur\u0103 este important\u0103. Centrala este echipat\u0103 cu arz\u0103tor automat pe pele\u021bi, func\u021bionarea cu \u00eenc\u0103rcare manual\u0103 a combustibilului nu este prev\u0103zut\u0103 de proiectarea cazanului. Recipient de cenusa glisant, Cazan pe peleti FOCUS 150 kW, Cazan pe peleti 60 kW FOCUS, Cazan pe peleti 70 kW FOCUS, Cazan pe peleti 80 kW FOCUS\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-2-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_641763946 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3840688915\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Poti alege orice cazan din gama noastra pentru proiecte mari va recomandam cazane pe peleti cu curatare pneumatica pentru incalzirea piscinelor.<\/p>\n\t\t\n<style>\n#text-3840688915 {\n  color: rgb(0,0,0);\n}\n#text-3840688915 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/shop\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-864531522\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_621468496\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5.png\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/2-5-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_621468496 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1395789140\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Seturile de conducte hidraulice Victaulic premium FOCUS reduc costurile cu for\u021ba de munc\u0103 \u00een timpul instal\u0103rii \u0219i prelungesc durata de via\u021b\u0103 a cazanului.<\/p>\n\t\t\n<style>\n#text-1395789140 {\n  color: rgb(0,0,0);\n}\n#text-1395789140 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/komplektuyushhie-pelletnyh-gorelok-i-tverdotoplivnyh-kotlov\/gidravlicheskie-uzly\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1636837224\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1174418685\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1.png\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/26-1-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1174418685 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3783185025\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Un bunc\u0103r de pele\u021bi este parte integrant\u0103 a oric\u0103rei \u00eenc\u0103peri de cazane pe pele\u021bi FOCUS TERMO ofer\u0103 modele pentru diferite sarcini \u0219i solu\u021bii: pentru case \u0219i ansambluri.<\/p>\n\t\t\n<style>\n#text-3783185025 {\n  color: rgb(0,0,0);\n}\n#text-3783185025 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/komplektuyushhie-pelletnyh-gorelok-i-tverdotoplivnyh-kotlov\/pelletnye-bunkery\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1427174534\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1642535681\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1020\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-1024x1024.jpg 1024w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-100x100.jpg 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-510x510.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-300x300.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-150x150.jpg 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-768x768.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-1536x1536.jpg 1536w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-2048x2048.jpg 2048w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6-12x12.jpg 12w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/03\/7-6.jpg 1000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1642535681 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-788468044\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Sistemul de cea\u021b\u0103 iluminat\u0103 poate fi folosit pentru a decora piscina \u0219i pentru a reduce temperatura aerului.<\/p>\n\t\t\n<style>\n#text-788468044 {\n  color: rgb(0,0,0);\n}\n#text-788468044 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/sistemy-tumanoobrazovaniya-focus\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1771167172\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_355588981\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:55px 0px 75px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"508\" height=\"334\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/ecomax860p.jpg\" class=\"attachment-large size-large\" alt=\"EcoMax860P\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/ecomax860p.jpg 508w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/ecomax860p-300x197.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/ecomax860p-18x12.jpg 18w\" sizes=\"auto, (max-width: 508px) 100vw, 508px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_355588981 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-919714287\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Automatizarea climatiz\u0103rii controleaz\u0103 cazanele FOCUS \u0219i permite implementarea unor sisteme complexe de control al \u00eenc\u0103lzirii cu reglare a vremii.<\/p>\n\t\t\n<style>\n#text-919714287 {\n  color: rgb(0,0,0);\n}\n#text-919714287 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/komplektuyushhie-pelletnyh-gorelok-i-tverdotoplivnyh-kotlov\/avtomatika-kontrolya-klimata\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-590151913\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1870985759\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:55px 0px 80px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"650\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/07\/sistema-1-1024x653.png\" class=\"attachment-large size-large\" alt=\"Sistem de internet EcoNet. Cazan cu climatizare. Controlul cazanului prin internet\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/07\/sistema-1-1024x653.png 1024w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/07\/sistema-1-510x325.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/07\/sistema-1-300x191.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/07\/sistema-1-768x489.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/07\/sistema-1-18x12.png 18w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/07\/sistema-1.png 1000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1870985759 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1095373697\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Mediul controlat de software EcoNet va ajuta la organizarea monitoriz\u0103rii \u00eenc\u0103lzirii piscinei \u0219i la reglarea de la distan\u021b\u0103 a parametrilor de \u00eenc\u0103lzire.<\/p>\n\t\t\n<style>\n#text-1095373697 {\n  color: rgb(0,0,0);\n}\n#text-1095373697 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/komplektuyushhie-pelletnyh-gorelok-i-tverdotoplivnyh-kotlov\/internet-sistema-upravleniya-rabotoj-ustrojstv-focus-econet\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1029532385\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1029532385 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3690317450\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\" style=\"font-size: 180%; font-weight: 900;\">Co\u0219uri de pele\u021bi disponibile<\/h2>\n<h3>pentru orice sarcin\u0103 de \u00eenc\u0103lzire a piscinei<\/h3>\n<p style=\"font-size: 190%; color: #fab331;\">FOCUS TERMO<\/p>\n\t\t\n<style>\n#text-3690317450 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-963254883\">\n\n\t<div id=\"col-1179814639\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_154148830\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1.png\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/20-1-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_154148830 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2989916577\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Mini bunc\u0103rele de pele\u021bi cu unul sau dou\u0103 melc sunt utilizate \u00een camerele cazanelor de acas\u0103 \u0219i \u00eenc\u0103lzirea piscinei \u00een zonele de gr\u0103din\u0103.<\/p>\n\t\t\n<style>\n#text-2989916577 {\n  color: rgb(0,0,0);\n}\n#text-2989916577 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/komplektuyushhie-pelletnyh-gorelok-i-tverdotoplivnyh-kotlov\/pelletnye-bunkery\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2037782980\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_825637293\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5.jpg\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5.jpg 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5-100x100.jpg 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5-510x510.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5-300x300.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5-150x150.jpg 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5-768x768.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/03-5-12x12.jpg 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_825637293 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2989547369\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Un bunc\u0103r de pele\u021bi pentru cazane \u00een cascad\u0103 de mare putere este instalat pentru \u00eenc\u0103lzirea piscinelor din complexele sportive.<\/p>\n\t\t\n<style>\n#text-2989547369 {\n  color: rgb(0,0,0);\n}\n#text-2989547369 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/komplektuyushhie-pelletnyh-gorelok-i-tverdotoplivnyh-kotlov\/pelletnye-bunkery\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-572737704\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_574842397\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5.png\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/01-5-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_574842397 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-539216424\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Un bunc\u0103r de pele\u021bi de volum crescut va putea asigura func\u021bionarea unei camere de cazane pentru \u00eenc\u0103lzirea piscinei unui centru de birouri.<\/p>\n\t\t\n<style>\n#text-539216424 {\n  color: rgb(0,0,0);\n}\n#text-539216424 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/komplektuyushhie-pelletnyh-gorelok-i-tverdotoplivnyh-kotlov\/pelletnye-bunkery\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Selecta\u021bi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1644914568\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1644914568 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1387431536\" class=\"text\">\n\t\t\n<p style=\"font-size: 190%; color: #fab331;\">FOCUS TERMO<\/p>\n<h2 class=\"uppercase\" style=\"font-size: 180%; font-weight: 900;\">Lider \u00een produc\u021bia de cazane<\/h2>\n\t\t\n<style>\n#text-1387431536 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1215994398\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1215994398 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-139541720\">\n\n\t<div id=\"col-349020588\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1932030421\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8.png\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/kplap-8-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1932030421 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-162593609\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Fiecare cazan FOCUS TERMO are un design proprietar cu un schimb\u0103tor de c\u0103ldur\u0103 eterogen (tub de foc \u0219i plac\u0103). Acest lucru evit\u0103 problema utiliz\u0103rii combustibilului cu con\u021binut ridicat de cenu\u0219\u0103 \u0219i cre\u0219te <strong>Eficien\u021b\u0103 p\u00e2n\u0103 la 96%<\/strong>.<\/p>\n\t\t\n<style>\n#text-162593609 {\n  color: rgb(0,0,0);\n}\n#text-162593609 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-249633733\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_791801353\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5.png\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/02\/palnik-1mvt-5-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_791801353 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2802051929\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Arz\u0103toarele sofisticate de tip flare sunt oferite \u00een modele cu putere record, ceea ce face posibil\u0103 arderea combustibilului peletizat la orice scar\u0103, asigur\u00e2nd conversia complet\u0103 a gazelor de piroliz\u0103 \u00een energie termic\u0103.<\/p>\n\t\t\n<style>\n#text-2802051929 {\n  color: rgb(0,0,0);\n}\n#text-2802051929 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-61174592\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1021656711\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1020\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-1024x1024.png\" class=\"attachment-large size-large\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-1024x1024.png 1024w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1-12x12.png 12w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/obvyazka-3kh-1.png 1000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1021656711 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2288293648\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Unitatile hidraulice Victaulic bazate pe conceptul de conectare nesudata sunt considerate fitinguri premium pentru sistemele de incalzire de inalta incredere, cele mai bune oferite pe piata mondiala.<\/p>\n\t\t\n<style>\n#text-2288293648 {\n  color: rgb(0,0,0);\n}\n#text-2288293648 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-450396605\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"message-box relative dark\" style=\"padding-top:10px;padding-bottom:10px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(250, 211, 75);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n<div class=\"row align-middle align-center\"  id=\"row-1432609748\">\n\n\t<div id=\"col-1546637258\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-404759989\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-404759989 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-667010039\" class=\"text\">\n\t\t\n<p style=\"font-size: 90%;\">Sistemele de incalzire cu cazane pe peleti sunt o solutie fiabila si economica pentru incalzirea piscinelor de orice dimensiune, cu conditia unei autonomii complete fata de retelele principale, economii la pretul gazului 70% si utilizarea reglementarii meteo.<\/p>\n<p><strong>SRL \u201eAqua Empire\u201d<\/strong>:<br \/>Telefon: <a href=\"tel:+38067612 0614\">+380 67 612 06 14<\/a><br \/>E-mail: <a \nhref=\"mailto:Akbass@ukr.net\">Akbass@ukr.net<\/a><\/p>\n\t\t\n<style>\n#text-667010039 {\n  color: rgb(0,0,0);\n}\n#text-667010039 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1447777027\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1447777027 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1852506323\" class=\"col medium-5 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<a data-animate=\"bounceInUp\" href=\"tel:+38067612%200614\" class=\"button white is-outline is-large\" style=\"border-radius:99px;\">\n\t<i class=\"icon-phone\" aria-hidden=\"true\"><\/i>\t<span>+380 67 612 06 14<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-2054577082\" class=\"gap-element clearfix show-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2054577082 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<\/div><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-center\"  id=\"row-1272099359\">\n\n\t<div id=\"col-741852220\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-501032184\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-501032184 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-796392268\" class=\"text\">\n\t\t\n<h2>Incalzirea piscinelor<\/h2>\n<p style=\"font-size: 190%; color: #fab331;\">FOCUS TERMO ePOOL<\/p>\n<h3 style=\"color: #464646;\">la preturi accesibile<\/h3>\n\t\t\n<style>\n#text-796392268 {\n  color: rgb(0,0,0);\n}\n#text-796392268 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1163066990\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-zoom-long dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom-1536x864.jpg\" class=\"attachment-1536x1536 size-1536x1536\" alt=\"Incalzire piscina FOCUS TERMO ePOOL\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom-1536x864.jpg 1536w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom-510x287.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom-300x169.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom-1024x576.jpg 1024w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom-768x432.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom-18x10.jpg 18w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/dom-s-bassejnom.jpg 1000w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1163066990 {\n  width: 96%;\n}\n@media (min-width:550px) {\n  #image_1163066990 {\n    width: 80%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>&nbsp;<\/p>\n\t<div id=\"gap-991622887\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-991622887 {\n  padding-top: 80px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-1918379430\">\n\n\t<div id=\"col-1801641290\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-2762939590\" class=\"text\">\n\t\t\n<h3>Circuite separate<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Incalzirea piscinei poate fi implementata cu diferite circuite, asigurand temperaturi diferite in cada cu hidromasaj, zona pentru copii si piscina principala.<\/p>\n\t\t\n<style>\n#text-2762939590 {\n  color: rgb(0, 0, 0);\n}\n#text-2762939590 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1801641290 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2134755036\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-2660267416\" class=\"text\">\n\t\t\n<h3>Folose\u0219te AI vocal<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Pe l\u00e2ng\u0103 panourile tactile, pute\u021bi utiliza SIRI pentru a controla aplica\u021biile mobile incluse \u00een \u00eenc\u0103lzirea piscinei.<\/p>\n\t\t\n<style>\n#text-2660267416 {\n  color: rgb(0, 0, 0);\n}\n#text-2660267416 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2134755036 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2141719324\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-3197002342\" class=\"text\">\n\t\t\n<h3>\u00cenc\u0103lzirea oric\u0103ror piscine<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Orice scar\u0103 a cazanului este o tr\u0103s\u0103tur\u0103 distinctiv\u0103 a FOCUS TERMO. \u00cenc\u0103lzirea unei piscine cu clim\u0103 controlat\u0103 se poate face folosind o mini-central\u0103 sau un cazan \u00een cascad\u0103.<\/p>\n\t\t\n<style>\n#text-3197002342 {\n  color: rgb(0, 0, 0);\n}\n#text-3197002342 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2141719324 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2021530528\" class=\"col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(250, 211, 75);border-width:1px 0px 11px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"text-650709931\" class=\"text\">\n\t\t\n<h3>Camere de cazane modulare<\/h3>\n<p style=\"font-size: 90%; line-height: 1.6;\">Pute\u021bi instala o camer\u0103 de cazane modular\u0103 special pentru \u00eenc\u0103lzirea unei piscine f\u0103r\u0103 a fi nevoie de lucr\u0103ri de construc\u021bie costisitoare.<\/p>\n\t\t\n<style>\n#text-650709931 {\n  color: rgb(0, 0, 0);\n}\n#text-650709931 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2021530528 > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-754580275\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-754580275 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-147102020\">\n\n\t<div id=\"col-1799197758\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-80951217\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1119709224\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_236107509\">\n\t\t<a class=\"\" href=\"\/ro\/tverdotoplivnye-pelletnye-kotly\/mono-pellet-20-kvt-focus-diapazon-moshhnosti-5-30kvt\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30.png\" class=\"attachment-large size-large\" alt=\"Cazan mono-pele\u021bi 60 kW. Cazan pe pele\u021bi de uz casnic Mono-pele\u021bi 50 kW, cazan pe pele\u021bi Mono-pele\u021bi 75 kW, cazan pe pele\u021bi Mono-pele\u021bi 90 kW cu climatizare \u00een format monobloc.\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2023\/11\/30-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_236107509 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_236107509 {\n    width: 83%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1119709224 {\n  width: 60%;\n}\n#text-box-1119709224 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-80951217 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1783658857\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"font-size: 140%; color: #fab331;\">Cazan casnic pe peleti<\/h3>\n<p style=\"font-size: 90%; color: black;\">Utiliza\u021bi o mini-cazan\u0103 pe pele\u021bi, echipat\u0103 \u0219i cu un microcontroler PLUM EcoMax, pentru a \u00eenc\u0103lzi piscinele de gr\u0103din\u0103 \u00eentr-o camer\u0103 de cazane individual\u0103.<\/p>\n\t<div id=\"gap-1613226059\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1613226059 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/tverdotoplivnye-pelletnye-kotly\/mono-pellet-20-kvt-focus-diapazon-moshhnosti-5-30kvt\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Cump\u0103r\u0103<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-843211483\">\n\n\t<div id=\"col-185513962\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1769903999\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-572087260\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1369317409\">\n\t\t<a class=\"\" href=\"\/ro\/tverdotoplivnye-kotly-dlya-gorelok\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"510\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva.jpg\" class=\"attachment-large size-large\" alt=\"Cazane pe combustibil solid cu arzator pe peleti. Cazan pe pele\u021bi cu \u00eenc\u0103rcare manual\u0103 op\u021bional\u0103 a combustibilului TT\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-100x100.jpg 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-300x300.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-150x150.jpg 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/pelletnyj-kotel-s-opcionalnoj-ruchnoj-zagruzkoj-tt-topliva-12x12.jpg 12w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1369317409 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_1369317409 {\n    width: 83%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-572087260 {\n  width: 60%;\n}\n#text-box-572087260 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1769903999 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1591416507\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"font-size: 140%; color: #fab331;\">Cazan cu arzator pe peleti<\/h3>\n<p style=\"font-size: 90%; color: black;\">Ideal pentru \u00eenc\u0103lzirea piscinei hotelului OFFGRID cu costuri minime de \u00eenc\u0103lzire. Folosind o cascad\u0103 de astfel de cazane, pute\u021bi organiza iarna \u00eenc\u0103lzirea piscinelor exterioare din sta\u021biunile de schi \u0219i pute\u021bi oferi turi\u0219tilor un serviciu unic.<\/p>\n\t<div id=\"gap-432130844\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-432130844 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/tverdotoplivnye-kotly-dlya-gorelok\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Cump\u0103r\u0103<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-873823486\">\n\n\t<div id=\"col-1400943008\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1328759381\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-228213605\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1531456601\">\n\t\t<a class=\"\" href=\"\/ro\/pelletnye-gorelki-focus\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1536\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-1536x1536.jpg\" class=\"attachment-1536x1536 size-1536x1536\" alt=\"Cazan pe pele\u021bi\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-1536x1536.jpg 1536w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-100x100.jpg 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-510x510.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-300x300.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-1024x1024.jpg 1024w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-150x150.jpg 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-768x768.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-2048x2048.jpg 2048w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1-12x12.jpg 12w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/mg_9529-1.jpg 1000w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1531456601 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_1531456601 {\n    width: 86%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-228213605 {\n  width: 60%;\n}\n#text-box-228213605 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1328759381 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1128112768\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"font-size: 140%; color: #fab331;\">Cazane pe pele\u021bi de mare putere<\/h3>\n<p style=\"font-size: 90%; color: black;\">Cazanele pe pele\u021bi de mare putere pot fi instalate \u00eentr-un cazan modular compact, care va asigura \u00eenc\u0103lzirea unei piscine mari \u00eentr-un centru comercial sau complex sportiv.<\/p>\n\t<div id=\"gap-1636053437\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1636053437 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/pelletnye-gorelki-focus\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Cump\u0103r\u0103<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1207622650\">\n\n\t<div id=\"col-321504822\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1911264904\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1730015413\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2003234277\">\n\t\t<a class=\"\" href=\"\/ro\/samoochistnye-pelletnye-kotly\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4.png\" class=\"attachment-1536x1536 size-1536x1536\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4.png 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-12x12.png 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_2003234277 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_2003234277 {\n    width: 86%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1730015413 {\n  width: 60%;\n}\n#text-box-1730015413 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1911264904 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-690328968\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"font-size: 140%; color: #fab331;\">Cazan pe peleti cu curatare pneumatica<\/h3>\n<p style=\"font-size: 90%; color: black;\">Cazanele cu autocur\u0103\u021bare pe pele\u021bi FOCUS TERMO sunt ideale pentru \u00eenc\u0103lzirea piscinei unui apart-hotel privat OFFGRID cu personal redus, deoarece nu necesit\u0103 \u00eentre\u021binere \u0219i cur\u0103\u021bare frecvent\u0103.<\/p>\n\t<div id=\"gap-1043719811\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1043719811 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/samoochistnye-pelletnye-kotly\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Cump\u0103r\u0103<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1468000664\">\n\n\t<div id=\"col-1085754750\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-204219292\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1961940741\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1001379950\">\n\t\t<a class=\"\" href=\"\/ro\/modulnye-kotelnye-kupit-v-ukraine\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-1.jpg\" class=\"attachment-1536x1536 size-1536x1536\" alt=\"Camere de cazane modulare FOCUS\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-1.jpg 750w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-1-510x680.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-1-225x300.jpg 225w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-1-768x1024.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/03\/zobrazhennya_viber_2024-03-06_10-39-25-193-1-9x12.jpg 9w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1001379950 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_1001379950 {\n    width: 68%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1961940741 {\n  width: 60%;\n}\n#text-box-1961940741 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-204219292 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-319308903\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"font-size: 140%; color: #fab331;\">Cazan\u0103 modular\u0103<\/h3>\n<p style=\"font-size: 90%; color: black;\">Un cazan modular pentru \u00eenc\u0103lzirea unei piscine este o solu\u021bie ideal\u0103 pentru gospod\u0103riile private \u0219i centrele comerciale mari, deoarece conectarea cazanului nu necesit\u0103 lucr\u0103ri de construc\u021bie, iar structura cadrului seam\u0103n\u0103 cu o cl\u0103dire compact\u0103 de gr\u0103din\u0103.<\/p>\n\t<div id=\"gap-891492618\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-891492618 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/ro\/modulnye-kotelnye-kupit-v-ukraine\/\" class=\"button success is-outline\" style=\"border-radius:99px;\">\n\t\t<span>Cump\u0103r\u0103<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-867648655\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-867648655 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp;<\/p>","protected":false},"author":1,"featured_media":9544,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-header-on-scroll.php","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-9261","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/pages\/9261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/comments?post=9261"}],"version-history":[{"count":0,"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/pages\/9261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/media\/9544"}],"wp:attachment":[{"href":"https:\/\/firebox.com.ua\/ro\/wp-json\/wp\/v2\/media?parent=9261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}