{"id":17,"date":"2019-07-04T09:11:08","date_gmt":"2019-07-04T09:11:08","guid":{"rendered":"https:\/\/jupiterx.artbees.net\/energy\/?page_id=17"},"modified":"2019-07-04T09:11:08","modified_gmt":"2019-07-04T09:11:08","slug":"services","status":"publish","type":"page","link":"https:\/\/firebox.com.ua\/cs\/services\/","title":{"rendered":"Technick\u00fd servis: mont\u00e1\u017e kotle"},"content":{"rendered":"<section class=\"section show-for-medium\" id=\"section_124098315\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-371911035\">\n\n\t<div id=\"col-577196293\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-949344885\">\n\n\t<div id=\"col-416313243\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_766009061\">\n\t\t<a class=\"\" href=\"\/cs\/kak-vybrat-kotel\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-300x300.png\" class=\"attachment-medium size-medium\" alt=\"- -\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-300x300.png 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-100x100.png 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-510x510.png 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-150x150.png 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-768x768.png 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4-12x12.png 12w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/04\/kplap-do150kvt-4.png 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_766009061 {\n  width: 73%;\n}\n@media (min-width:550px) {\n  #image_766009061 {\n    width: 55%;\n  }\n}\n@media (min-width:850px) {\n  #image_766009061 {\n    width: 100%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2005339248\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Vlastn\u00ed v\u00fdrobn\u00ed z\u00e1kladna<\/h3>\n<p>FOCUS TERMO vyr\u00e1b\u00ed topn\u00e1 za\u0159\u00edzen\u00ed ve vlastn\u00ed pln\u00e9 cyklick\u00e9 v\u00fdrob\u011b od f\u00e1ze n\u00e1vrhu a\u017e po testov\u00e1n\u00ed.<\/p>\n<a href=\"\/cs\/about-us\/\" class=\"button primary is-outline\" >\n\t\t<span>\u010d\u00edst<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1031187919\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1176043974\">\n\n\t<div id=\"col-1175156187\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_674009780\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"269\" height=\"300\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/zobrazhennya_viber_2024-03-06_10-39-25-193-2-e1715530354344-269x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Modul\u00e1rn\u00ed kotelny na Ukrajin\u011b zakoup\u00edte u FOCUS TERMO\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/zobrazhennya_viber_2024-03-06_10-39-25-193-2-e1715530354344-269x300.jpg 269w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/zobrazhennya_viber_2024-03-06_10-39-25-193-2-e1715530354344-510x569.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/zobrazhennya_viber_2024-03-06_10-39-25-193-2-e1715530354344-919x1024.jpg 919w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/zobrazhennya_viber_2024-03-06_10-39-25-193-2-e1715530354344-768x856.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/zobrazhennya_viber_2024-03-06_10-39-25-193-2-e1715530354344-11x12.jpg 11w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2024\/05\/zobrazhennya_viber_2024-03-06_10-39-25-193-2-e1715530354344.jpg 897w\" sizes=\"auto, (max-width: 269px) 100vw, 269px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_674009780 {\n  width: 81%;\n}\n@media (min-width:550px) {\n  #image_674009780 {\n    width: 70%;\n  }\n}\n@media (min-width:850px) {\n  #image_674009780 {\n    width: 100%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-73671344\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Dokumentace<\/h3>\n<p>Pro referenci a reference pou\u017eijte pros\u00edm na\u0161i dokumentaci. FOCUS TERMO V\u00e1m v\u017edy dok\u00e1\u017ee poskytnout celou \u0161k\u00e1lu slu\u017eeb pro v\u00fdrobu topn\u00fdch za\u0159\u00edzen\u00ed v\u010detn\u011b zak\u00e1zkov\u00e9 v\u00fdroby.<\/p>\n<a href=\"\/cs\/dokumentaciya-po-oborudovaniyu-tm-focus\/\" class=\"button primary is-outline\" >\n\t\t<span>\u010d\u00edst<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_124098315 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_465988441\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"484\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/01\/cushka-860-1.jpg\" class=\"bg attachment- size-\" alt=\"V\u00fdroba kotl\u016f FOCUS\" title=\"- -\">\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:1300px\" id=\"row-179493625\">\n\n\t<div id=\"col-1506405530\" class=\"col medium-12 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-974895097\">\n\n\t<div id=\"col-117637478\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1981923889\" class=\"text\">\n\t\t\n<h3>01<\/h3>\n\t\t\n<style>\n#text-1981923889 {\n  font-size: 1.25rem;\n  text-align: left;\n  color: rgb(199, 146, 0);\n}\n#text-1981923889 > * {\n  color: rgb(199, 146, 0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:15px;margin-bottom:15px;max-width:50px;background-color:rgb(199, 146, 0);\"><\/div>\n<h5>Optim\u00e1ln\u00ed ceny<\/h5>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-670314792\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3146131998\" class=\"text\">\n\t\t\n<h3>02<\/h3>\n\t\t\n<style>\n#text-3146131998 {\n  font-size: 1.25rem;\n  text-align: left;\n  color: rgb(199, 146, 0);\n}\n#text-3146131998 > * {\n  color: rgb(199, 146, 0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:15px;margin-bottom:15px;max-width:50px;background-color:rgb(199, 146, 0);\"><\/div>\n<h5>Pr\u00e9miov\u00e1 kvalita<\/h5>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-416810354\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1486884337\" class=\"text\">\n\t\t\n<h3>03<\/h3>\n\t\t\n<style>\n#text-1486884337 {\n  font-size: 1.25rem;\n  text-align: left;\n  color: rgb(199, 146, 0);\n}\n#text-1486884337 > * {\n  color: rgb(199, 146, 0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:15px;margin-bottom:15px;max-width:50px;background-color:rgb(199, 146, 0);\"><\/div>\n<h5>Odborn\u00e9 poradenstv\u00ed<\/h5>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1506405530 > .col-inner {\n  margin: 0 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1506405530 > .col-inner {\n    margin: 350px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-1506405530 > .col-inner {\n    margin: 230px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_465988441 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 700px;\n}\n#section_465988441 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.33);\n}\n@media (min-width:550px) {\n  #section_465988441 {\n    min-height: 500px;\n  }\n}\n@media (min-width:850px) {\n  #section_465988441 .section-bg-overlay {\n    background-color: rgba(0, 0, 0, 0.15);\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_10063022\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-223829857\">\n\n\t<div id=\"col-329687492\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1539898940\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:-0px 0px 80px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1.jpg\" class=\"attachment-large size-large\" alt=\"Prod\u00e1m Kotel na tuh\u00e1 paliva 300+ kW FOCUS\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1.jpg 1000w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1-100x100.jpg 100w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1-510x510.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1-300x300.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1-150x150.jpg 150w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1-768x768.jpg 768w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/300-plus-kwt-1-12x12.jpg 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1539898940 {\n  width: 80%;\n}\n@media (min-width:850px) {\n  #image_1539898940 {\n    width: 100%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-522843284\" class=\"col medium-12 small-12 large-6\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(199, 146, 0);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1133379549\" class=\"text\">\n\t\t\n<h1 style=\"font-size: 140%;\">Mont\u00e1\u017e kotl\u016f a servis kotelen na pelety<\/h1>\n\t\t\n<style>\n#text-1133379549 {\n  font-size: 1.25rem;\n}\n@media (min-width:550px) {\n  #text-1133379549 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:25px;margin-bottom:25px;max-width:100px;background-color:rgb(255, 255, 255);\"><\/div>\n<p>Instalace topn\u00fdch kotl\u016f FOCUS na granule na pelety zaj\u00edm\u00e1 st\u00e1le v\u00edce na\u0161ich z\u00e1kazn\u00edk\u016f. Spole\u010dnost FireBox na na\u0161ich str\u00e1nk\u00e1ch instaluje celou \u0159adu topn\u00fdch za\u0159\u00edzen\u00ed: od domovn\u00edch kotelen a\u017e po velk\u00e9 pr\u016fmyslov\u00e9 tepeln\u00e9 elektr\u00e1rny.<\/p>\n<p>FireBox navrhuje a instaluje kotle. Cena mont\u00e1\u017ee z\u00e1vis\u00ed na charakteru pr\u00e1ce, po\u010dtu zapojen\u00fdch kotl\u016f na tuh\u00e1 paliva a slo\u017eitosti p\u0159ipojen\u00ed k topn\u00fdm okruh\u016fm.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-522843284 > .col-inner {\n  padding: 40px 40px 40px 40px;\n  margin: -75px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-522843284 > .col-inner {\n    padding: 30px 80px 60px 80px;\n    margin: -50px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-522843284 > .col-inner {\n    padding: 20px 80px 60px 80px;\n    margin: -150px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-783108552\">\n\n\t<div id=\"col-183342043\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1439656340\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\">P\u0159\u00edklad uspo\u0159\u00e1d\u00e1n\u00ed pece o v\u00fdkonu 1 MW<\/h2>\n<h3 class=\"thin-font\">s automatick\u00fdm vybalov\u00e1n\u00edm big bag\u016f do n\u00e1sypky o objemu 6 m3<\/h3>\n\t\t\n<style>\n#text-1439656340 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-389339139\">\n\n\t<div id=\"col-700193002\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_82428193\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"686\" height=\"596\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskim-rasstarivaniem-big-bjegov.jpg\" class=\"attachment-large size-large\" alt=\"Peletov\u00e1 kotelna na 1 MW s automatick\u00fdm vybalov\u00e1n\u00edm big-bagu\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskim-rasstarivaniem-big-bjegov.jpg 686w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskim-rasstarivaniem-big-bjegov-510x443.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskim-rasstarivaniem-big-bjegov-300x261.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskim-rasstarivaniem-big-bjegov-14x12.jpg 14w\" sizes=\"auto, (max-width: 686px) 100vw, 686px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_82428193 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-622718820\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_305989314\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"702\" height=\"596\" src=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskoj-zagruzkoj-pellet-v-bunker.jpg\" class=\"attachment-large size-large\" alt=\"Peletov\u00e1 kotelna 1 MW s automatick\u00fdm nakl\u00e1d\u00e1n\u00edm pelet do z\u00e1sobn\u00edku\" srcset=\"https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskoj-zagruzkoj-pellet-v-bunker.jpg 702w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskoj-zagruzkoj-pellet-v-bunker-510x433.jpg 510w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskoj-zagruzkoj-pellet-v-bunker-300x255.jpg 300w, https:\/\/firebox.com.ua\/wp-content\/uploads\/2022\/07\/pelletnaya-kotelnaya-na-1-mvt-s-avtomaticheskoj-zagruzkoj-pellet-v-bunker-14x12.jpg 14w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" title=\"- -\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_305989314 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1694503233\">\n\n\t<div id=\"col-1644382579\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"font-size: 95%;\">Instalace kotelny m\u016f\u017ee b\u00fdt provedena na b\u00e1zi plynov\u00fdch, elektrick\u00fdch kotl\u016f a kotl\u016f na tuh\u00e1 paliva. Hybridn\u00ed kotelnu dok\u00e1\u017ee na\u0161e spole\u010dnost navrhnout, pokud je pot\u0159eba zachovat dopl\u0148kov\u00fd zdroj tepla. To je typick\u00e9 sp\u00ed\u0161e pro vyt\u00e1p\u011bn\u00ed dom\u00e1cnost\u00ed.<\/p>\n<p style=\"font-size: 95%;\">Pro pr\u016fmyslov\u00e9 \u00fa\u010dely FireBox navrhuje kotelny na pelety s automatick\u00fdm p\u0159ikl\u00e1d\u00e1n\u00edm tuh\u00e9ho paliva, jak ukazuje p\u0159\u00edklad. Pro z\u00edsk\u00e1n\u00ed rady se potenci\u00e1ln\u00ed kupuj\u00edc\u00ed mus\u00ed rozhodnout o v\u00fdb\u011bru topn\u00fdch kotl\u016f, na\u0161i specialist\u00e9 se postaraj\u00ed o zbytek - od n\u00e1vrhu a\u017e po instalaci.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-987924796\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Firebox m\u016f\u017ee nab\u00eddnout instalaci kotl\u016f o celkov\u00e9m v\u00fdkonu a\u017e 2,2 MW, provozovan\u00fdch na pelety a poskytuj\u00edc\u00edch levnou energii bez nutnosti v\u00fdb\u011bru certifikovan\u00fdch pelet.<\/p>\n<p>Obvykle se takov\u00e1 instalace prov\u00e1d\u00ed s kask\u00e1dov\u00fdm p\u0159ipojen\u00edm kotl\u016f na tuh\u00e1 paliva. Tento typ instalace umo\u017e\u0148uje vypnout jeden z gener\u00e1tor\u016f tepla bez po\u0161kozen\u00ed provozu kotelny. Na\u0161e spole\u010dnost nab\u00edz\u00ed \u0159adu stojac\u00edch kotl\u016f, je to zp\u016fsobeno velkou hmotnost\u00ed za\u0159\u00edzen\u00ed a nutnost\u00ed jejich stacion\u00e1rn\u00ed instalace.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-center\"  id=\"row-197944251\">\n\n\t<div id=\"col-1173203960\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center;\"><strong>\u00dakolem na\u0161eho t\u00fdmu je, aby va\u0161e vyt\u00e1p\u011bn\u00ed bylo pohodln\u00e9, softwarov\u011b \u0159\u00edzen\u00e9 a levn\u00e9, d\u016fle\u017eitou roli v tom hraje instalace kotl\u016f <a href=\"\/cs\/shop\/\">instalace kotle<\/a>!<\/strong><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:2px;background-color:rgb(50, 42, 42);\"><\/div><\/div>\n<div class=\"row row-collapse row-full-width align-middle\"  id=\"row-1498770154\">\n\n\t<div id=\"col-1819165765\" class=\"col medium-12 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-center dark\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2877452891\" class=\"text\">\n\t\t\n<h2>Z\u00edskejte na\u0161i nab\u00eddku, pokud m\u00e1te z\u00e1jem o instalaci kotle!<\/h2>\n<p>P\u0159eve\u010fte sv\u00e9 podnik\u00e1n\u00ed na pelety s pomoc\u00ed na\u0161ich odborn\u00edk\u016f.<br \/>\n\t\t\n<style>\n#text-2877452891 {\n  color: rgb(1, 1, 1);\n}\n#text-2877452891 > * {\n  color: rgb(1, 1, 1);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"social-icons follow-icons\" ><a href=\"#\" target=\"_blank\" data-label=\"Facebook\" class=\"icon plain tooltip facebook\" title=\"Sledujte n\u00e1s na Facebooku\" aria-label=\"Sledujte n\u00e1s na Facebooku\" rel=\"noopener nofollow\"><i class=\"icon-facebook\" aria-hidden=\"true\"><\/i><\/a><a href=\"#\" target=\"_blank\" data-label=\"Instagram\" class=\"icon plain tooltip instagram\" title=\"sledovat n\u00e1\u0161 Instagram\" aria-label=\"sledovat n\u00e1\u0161 Instagram\" rel=\"noopener nofollow\"><i class=\"icon-instagram\" aria-hidden=\"true\"><\/i><\/a><a href=\"#\" data-label=\"LinkedIn\" target=\"_blank\" class=\"icon plain tooltip linkedin\" title=\"Sledujte n\u00e1s na LinkedIn\" aria-label=\"Sledujte n\u00e1s na LinkedIn\" rel=\"noopener nofollow\"><i class=\"icon-linkedin\" aria-hidden=\"true\"><\/i><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1819165765 > .col-inner {\n  padding: 50px 30px 40px 30px;\n}\n@media (min-width:550px) {\n  #col-1819165765 > .col-inner {\n    padding: 70px 70px 50px 70px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-990494426\" class=\"col medium-12 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5072-o1\" lang=\"ru-RU\" dir=\"ltr\" data-wpcf7-id=\"5072\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/cs\/wp-json\/wp\/v2\/pages\/17#wpcf7-f5072-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktn\u00ed formul\u00e1\u0159\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/cs\/wp-json\/wp\/v2\/pages\/17#wpcf7-f5072-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5072\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ru_RU\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5072-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label style=\"color: white;\">Va\u0161e kontaktn\u00ed \u00fadaje:<\/label><br \/>\nn\u00e1zev<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-216\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"tv\u00e9 jm\u00e9no\" value=\"\" type=\"text\" name=\"text-216\" \/><\/span><br \/>\nE-mailem<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tv\u016fj e-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\nTelefon<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-435\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Va\u0161e telefonn\u00ed \u010d\u00edslo\" value=\"\" type=\"tel\" name=\"tel-435\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner button\" type=\"submit\" value=\"poslat\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"cs\"\/><\/form>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-990494426 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_10063022 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4534,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-17","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":0,"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/media\/4534"}],"wp:attachment":[{"href":"https:\/\/firebox.com.ua\/cs\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}